{"id":8569,"date":"2017-01-22T21:25:31","date_gmt":"2017-01-22T19:25:31","guid":{"rendered":"https:\/\/urb.bme.hu\/?p=8569"},"modified":"2021-06-28T16:10:39","modified_gmt":"2021-06-28T14:10:39","slug":"science-park-otletpalyazat","status":"publish","type":"post","link":"https:\/\/urb.bme.hu\/en\/science-park-otletpalyazat\/","title":{"rendered":"(HU) Science Park \u00d6tletp\u00e1ly\u00e1zat"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/urb.bme.hu\/hu\/wp-json\/wp\/v2\/posts\/8569\" class=\"qtranxs-available-language-link qtranxs-available-language-link-hu\" title=\"HU\">Hungarian<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Hungarian.<\/p>\n","protected":false},"author":2,"featured_media":16259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,56,12,55],"tags":[],"megjelenites":[],"esemeny_datum":[],"esemeny_tipus":[],"_links":{"self":[{"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/posts\/8569"}],"collection":[{"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/comments?post=8569"}],"version-history":[{"count":0,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/posts\/8569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/media\/16259"}],"wp:attachment":[{"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/media?parent=8569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/categories?post=8569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/tags?post=8569"},{"taxonomy":"megjelenites","embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/megjelenites?post=8569"},{"taxonomy":"esemeny_datum","embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/esemeny_datum?post=8569"},{"taxonomy":"esemeny_tipus","embeddable":true,"href":"https:\/\/urb.bme.hu\/en\/wp-json\/wp\/v2\/esemeny_tipus?post=8569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}